{"id":4090,"date":"2019-12-10T01:24:00","date_gmt":"2019-12-09T23:24:00","guid":{"rendered":"https:\/\/www.cabine.pt\/?p=4090"},"modified":"2020-10-07T23:16:40","modified_gmt":"2020-10-07T21:16:40","slug":"probest-seguros","status":"publish","type":"post","link":"https:\/\/www.cabine.pt\/es\/trabajos\/probest-seguros","title":{"rendered":"Probest Seguros"},"content":{"rendered":"<h5>Dise\u00f1o Visual de Probest Seguros. Website y branding.<\/h5>\n<p>Dise\u00f1o Visual de <a href=\"http:\/\/www.probestseguros.pt\" target=\"_blank\" rel=\"noopener noreferrer\">Probest Seguros<\/a>, una empresa de Seguros, especialista en consultor\u00eda, gesti\u00f3n de carteras de seguros y siniestros. Empresariales o particulares.<\/p>\n<blockquote><p>Asesor\u00eda y&nbsp; Servicio de Excelencia.<\/p><\/blockquote>\n<p>Una empresa enfocada en asesor\u00eda y prestar Servicios de Excelencia. Dedicada actividades de corretaje de seguros de forma independiente face \u00e0s companhias de seguros, baseando a sua actividade en an\u00e1lisis imparciales de contratos de seguros disponibles en el mercado que les permita asesorar al cliente teniendo en cuenta sus necesidades espec\u00edficas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"post-excerpt\">Dise\u00f1o Visual de Probest Seguros. Website y branding. Dise\u00f1o Visual de Probest Seguros, una empresa de Seguros, especialista en consultor\u00eda, gesti\u00f3n de carteras de seguros y siniestros. Empresariales&#8230;<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[217,223,224,220,213,222],"tags":[],"class_list":["post-4090","post","type-post","status-publish","format-gallery","hentry","category-217","category-223","category-224","category-disenovisual","category-trabajos","category-web-es","post_format-post-format-gallery"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6hLhL-13Y","_links":{"self":[{"href":"https:\/\/www.cabine.pt\/es\/wp-json\/wp\/v2\/posts\/4090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cabine.pt\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cabine.pt\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cabine.pt\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cabine.pt\/es\/wp-json\/wp\/v2\/comments?post=4090"}],"version-history":[{"count":2,"href":"https:\/\/www.cabine.pt\/es\/wp-json\/wp\/v2\/posts\/4090\/revisions"}],"predecessor-version":[{"id":4281,"href":"https:\/\/www.cabine.pt\/es\/wp-json\/wp\/v2\/posts\/4090\/revisions\/4281"}],"wp:attachment":[{"href":"https:\/\/www.cabine.pt\/es\/wp-json\/wp\/v2\/media?parent=4090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cabine.pt\/es\/wp-json\/wp\/v2\/categories?post=4090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cabine.pt\/es\/wp-json\/wp\/v2\/tags?post=4090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}